{"id":262,"date":"2021-08-05T09:23:27","date_gmt":"2021-08-05T12:23:27","guid":{"rendered":"https:\/\/sereena.com.br\/?page_id=262"},"modified":"2023-08-16T14:04:25","modified_gmt":"2023-08-16T17:04:25","slug":"aviso","status":"publish","type":"page","link":"https:\/\/safeplants.com.br\/index.php\/aviso\/","title":{"rendered":"AVISO"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"262\" class=\"elementor elementor-262\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e3c5c8 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"0e3c5c8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec15324\" data-id=\"ec15324\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a6b3808 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"a6b3808\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-73ea007\" data-id=\"73ea007\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7abf00 elementor-widget elementor-widget-image\" data-id=\"d7abf00\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 09-08-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/safeplants.com.br\/wp-content\/uploads\/2023\/08\/headder.png\" title=\"headder\" alt=\"headder\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80fa507 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"80fa507\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3fc15d3e\" data-id=\"3fc15d3e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47a6d74f elementor-widget elementor-widget-text-editor\" data-id=\"47a6d74f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 09-08-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>AVISO LEGAL<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5675a7c5 elementor-widget elementor-widget-text-editor\" data-id=\"5675a7c5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>INSTRU\u00c7\u00d5ES DE USO<\/p><p>O produto \u00e9 um inseticida sist\u00eamico do grupo qu\u00edmico dos neocotin\u00f3ides.<\/p><p>Classifica\u00e7\u00e3o<br \/>T\u00e9cnica de Aplica\u00e7\u00e3o:\u00a0Terrestre<br \/>Classe Agron\u00f4mica:\u00a0Inseticida<br \/>Toxicol\u00f3gica:\u00a04 &#8211; Produto Pouco T\u00f3xico<br \/>Inflamabilidade:\u00a0N\u00e3o inflam\u00e1vel<br \/>Corrosividade:\u00a0N\u00e3o corrosivo<br \/>Formula\u00e7\u00e3o:\u00a0Granulado Dispers\u00edvel (WG)<br \/>Modo de A\u00e7\u00e3o:\u00a0Sist\u00eamico<\/p><p>INSTRU\u00c7\u00d5ES DE USO<\/p><p>O produto \u00e9 um inseticida do tipo S\u00edlica amorfa.<\/p><p>Classifica\u00e7\u00e3o<br \/>T\u00e9cnica de Aplica\u00e7\u00e3o:\u00a0Terrestre<br \/>Nome qu\u00edmico: silicon dioxide <br \/>F\u00f3rmula bruta: SiO2 f<br \/>Grupo qu\u00edmico: Inorg\u00e2nico <br \/>Classe: Inseticida <br \/>Classifica\u00e7\u00e3o toxicol\u00f3gica:\u00a0Classe III\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>MODO DE APLICA\u00c7\u00c3O<\/p><p>Preparo de Calda<\/p><p>Para o preparo da calda, deve-se utilizar \u00e1gua de boa qualidade, livre de coloides em suspens\u00e3o (terra, argila ou mat\u00e9ria org\u00e2nica), a presen\u00e7a destes pode reduzir a efic\u00e1cia do produto.<br \/>O equipamento de pulveriza\u00e7\u00e3o a ser utilizado para a aplica\u00e7\u00e3o deve estar limpo de res\u00edduos de outro defensivo.<br \/>Preencher o tanque do pulverizador com \u00e1gua at\u00e9 a metade de sua capacidade; em seguida \u00e9 necess\u00e1rio que se fa\u00e7a uma pr\u00e9-dilui\u00e7\u00e3o em um recipiente n\u00e3o reativo (pl\u00e1stico, fibra de vidro), adicionando a dose recomendada para cada cultivo em 5 a 10 litros de \u00e1gua agitando-o com um bast\u00e3o pl\u00e1stico at\u00e9 que a pr\u00e9-calda esteja homog\u00eanea, assegurando-se a completa umecta\u00e7\u00e3o e dispers\u00e3o dos aglomerantes presentes na formula\u00e7\u00e3o, ap\u00f3s esta etapa, inserir a pr\u00e9-mistura no pulverizador, acrescentar o adjuvante indicado na propor\u00e7\u00e3o recomendada para o cultivo\/alvo e completar a capacidade do reservat\u00f3rio do pulverizador com \u00e1gua, mantendo sempre o sistema em agita\u00e7\u00e3o e retorno ligado durante todo o processo de preparo e pulveriza\u00e7\u00e3o para manter homog\u00eanea a calda de pulveriza\u00e7\u00e3o.<br \/>Prepare apenas a quantidade de calda necess\u00e1ria para completar o tanque de aplica\u00e7\u00e3o, pulverizando logo ap\u00f3s sua prepara\u00e7\u00e3o.<br \/>Na ocorr\u00eancia de algum imprevisto que interrompa a agita\u00e7\u00e3o da calda, agit\u00e1-la vigorosamente antes de reiniciar a aplica\u00e7\u00e3o.<br \/>No caso de quimiga\u00e7\u00e3o considerar a \u00e1rea a ser irrigada, calcular e dosar a quantidade do produto necess\u00e1ria para a aplica\u00e7\u00e3o da dose recomendada por hectare, seguindo a recomenda\u00e7\u00e3o do fabricante do sistema de irriga\u00e7\u00e3o e inje\u00e7\u00e3o.<\/p><p>Equipamentos Costais (manuais ou motorizados)<\/p><p>Utilizar pulverizador costal dotado de ponta de pulveriza\u00e7\u00e3o do tipo leque (jato plano), calibrando de forma a proporcionar perfeita cobertura com tamanho de gota m\u00e9dia a grossa e direcionando para o alvo desejado.<br \/>Observar para que a aplica\u00e7\u00e3o seja uniforme e que n\u00e3o ocorram sobreposi\u00e7\u00f5es, escorrimentos e nem deriva por movimentos n\u00e3o planejados pelo operador.<\/p><p>Equipamento estacion\u00e1rio manual (pistola)<\/p><p>Utilizar pulverizador estacion\u00e1rio munido de barra com ponta de pulveriza\u00e7\u00e3o do tipo leque (jato plano) ou com pistola com gatilho de abertura e fechamento dotado de ponta de pulveriza\u00e7\u00e3o hidr\u00e1ulica e calibrar o equipamento para que a cada acionamento, do gatilho, a vaz\u00e3o seja constante. Manter velocidade de deslocamento constante de modo que n\u00e3o se prejudique a condi\u00e7\u00e3o da forma\u00e7\u00e3o das gotas e mantenha o mesmo volume de calda em toda a \u00e1rea tratada. Realizar movimentos uniformes com a barra ou pistola evitando sobreposi\u00e7\u00f5es, deriva ou concentra\u00e7\u00e3o de calda em um \u00fanico ponto gerando, assim, escorrimento e desperd\u00edcio da calda.<\/p><p>Aplica\u00e7\u00e3o em bandeja<\/p><p>Utilizar pulverizador costal manual, com volume de calda de 250 mL para bandeja de 200 alv\u00e9olos. O c\u00e1lculo da quantidade de produto a ser aplicado em cada bandeja, dever\u00e1 ser feito previamente e proporcional ao n\u00famero de plantas a ser transplantado por hectare dependendo da cultura e espa\u00e7amento a serem adotados. Logo ap\u00f3s a aplica\u00e7\u00e3o recomenda-se repetir a aplica\u00e7\u00e3o da mesma forma com o mesmo volume de \u00e1gua para que seja feito o arraste do produto das folhas e ramos para o substrato, facilitando a absor\u00e7\u00e3o radicular.<\/p><p>Imers\u00e3o e Rega<\/p><p>Proceder a imers\u00e3o das bandejas com as mudas durante um per\u00edodo de 30 segundos, em seguida retir\u00e1-las e deixar escorrer o excesso de calda por um per\u00edodo de 2 minutos.<br \/>Rega: aplicar o produto sobre a planta, nas doses recomendadas, utilizando o volume de 1L de calda\/m\u00b2.<\/p><p>Aplica\u00e7\u00e3o via esguicho (drench)<\/p><p>Esta modalidade pode ser utilizada ap\u00f3s o transplantio de mudas. Aplicar o produto dilu\u00eddo em \u00e1gua na forma de jato dirigido planta a planta (esguicho) atrav\u00e9s de pulverizador manual, motorizado ou tratorizado, de forma que o produto atinja o caule e escorra at\u00e9 o solo, utilizando o volume de calda por planta e a dosagem recomendada por hectare do produto para o cultivo.<\/p><p>Pulverizadores de Barra<\/p><p>Utilizar pulverizadores tratorizados de barra ou autopropelidos, com pontas de pulveriza\u00e7\u00e3o hidr\u00e1ulicas, adotando o espa\u00e7amento entre pontas e altura da barra com rela\u00e7\u00e3o ao alvo recomendados pelo fabricante das pontas.<br \/>Certificar-se que a altura da barra \u00e9 a mesma com rela\u00e7\u00e3o ao alvo em toda sua extens\u00e3o, devendo esta altura ser adequada ao estagio de desenvolvimento da cultura de forma a permitir uma perfeita cobertura das plantas. O equipamento deve ser regulado e calibrado de forma a produzir espectro de gotas m\u00e9dias a grossas.<\/p><p>Jato Dirigido<\/p><p>Utilizar pulverizador autopropelido ou tratorizado de barra, dotado de ponta do tipo leque (jato plano) dirigido ao sulco de plantio, sobre os &#8220;toletes&#8221;, adotando o espa\u00e7amento entre pontas e altura da barra com rela\u00e7\u00e3o ao alvo que permita uma perfeita cobertura dos \u201ctoletes\u201d. Certificar-se que a altura da barra \u00e9 a mesma com rela\u00e7\u00e3o ao alvo em toda sua extens\u00e3o. O equipamento deve ser regulado e calibrado de forma a produzir espectro de gotas m\u00e9dias a grossas. Procedendo-se a cobertura imediatamente ap\u00f3s aplica\u00e7\u00e3o.<\/p><p>Hidropneum\u00e1ticos (Turbo-atomizadores)<\/p><p>Utilizar pulverizador tratorizado montado, semi-montado ou de arrasto, dotado de ponta do tipo cone vazio com espa\u00e7amento entre pontas determinado pelo fabricante. As pontas devem ser direcionadas para o alvo de acordo com cada cultura, as pontas superiores e inferiores podem ser desligados para que n\u00e3o seja feita a pulveriza\u00e7\u00e3o no solo ou acima do topo da cultura, al\u00e9m do emprego de pontas com perfil de gotas variando entre grossa e muito grossa nas posi\u00e7\u00f5es superiores, a fim de evitar a perda dessas gotas por deriva. A regulagem do ventilador deve oferecer energia suficiente para que as gotas sejam impulsionadas para o interior do dossel da cultura, conferindo a melhor cobertura no interior da estrutura da planta.<br \/>O equipamento deve ser regulado e calibrado de forma a produzir espectro de gotas m\u00e9dias a grossas.<\/p><p>Irriga\u00e7\u00e3o por gotejamento<\/p><p>Iniciar a inje\u00e7\u00e3o da calda com o produto ap\u00f3s o completo funcionamento do sistema de irriga\u00e7\u00e3o. Seguir as instru\u00e7\u00f5es do fabricante do sistema de irriga\u00e7\u00e3o para a melhor utiliza\u00e7\u00e3o do sistema dosador e de inje\u00e7\u00e3o, al\u00e9m da correta regulagem deste equipamento.<br \/>A inje\u00e7\u00e3o dos produtos pode ser efetuada utilizando-se diferentes m\u00e9todos e equipamentos. Por\u00e9m, independentemente do m\u00e9todo adotado, a qualidade dos resultados obtidos na quimiga\u00e7\u00e3o depende do c\u00e1lculo correto de vari\u00e1veis como taxa de inje\u00e7\u00e3o, quantidade do produto a ser injetada, volume do tanque de inje\u00e7\u00e3o, dose do produto a ser aplicada na \u00e1rea irrigada, concentra\u00e7\u00e3o do produto na \u00e1gua de irriga\u00e7\u00e3o, entre outros.<br \/>Al\u00e9m dos c\u00e1lculos operacionais feitos corretamente, \u00e9 necess\u00e1rio assegurar-se de que o sistema, tanto de irriga\u00e7\u00e3o quanto de inje\u00e7\u00e3o, est\u00e1 funcionando de acordo com os par\u00e2metros para os quais est\u00e1 ajustado, ou seja, que a vaz\u00e3o calculada corresponde \u00e0quela efetiva no sistema ou que a taxa de inje\u00e7\u00e3o desejada estar\u00e1 realmente ocorrendo no campo. Portanto, t\u00e3o importante quanto os c\u00e1lculos operacionais, \u00e9 tamb\u00e9m proceder \u00e0 calibra\u00e7\u00e3o peri\u00f3dica dos equipamentos.<\/p><p>Condi\u00e7\u00f5es clim\u00e1ticas<\/p><p>Temperatura: menor que 30\u00b0C;<br \/>Umidade do ar: maior que 55%;<br \/>Velocidade do vento: entre 3 e 10km\/h.<\/p><p>Recomenda\u00e7\u00f5es gerais para evitar deriva<\/p><p>&#8211; N\u00e3o permita que a deriva proveniente da aplica\u00e7\u00e3o atinja culturas vizinhas, \u00e1reas habitadas, leitos de rios e outras fontes de \u00e1gua, cria\u00e7\u00f5es e \u00e1reas de preserva\u00e7\u00e3o ambiental.<br \/>&#8211; Siga as restri\u00e7\u00f5es existentes na legisla\u00e7\u00e3o pertinente.<br \/>&#8211; O potencial de deriva \u00e9 determinado pela intera\u00e7\u00e3o de muitos fatores relativos ao equipamento de pulveriza\u00e7\u00e3o (independente dos equipamentos utilizados para a pulveriza\u00e7\u00e3o, o tamanho das gotas \u00e9 um dos fatores mais importantes para evitar a deriva) e ao clima (velocidade do vento, umidade e temperatura).<br \/>&#8211; O aplicador deve considerar todos estes fatores quando da decis\u00e3o de aplicar. Evitar a deriva \u00e9 responsabilidade do aplicador.<\/p><p>Di\u00e2metro das gotas<\/p><p>&#8211; A melhor estrat\u00e9gia de gerenciamento de deriva \u00e9 aplicar com o maior di\u00e2metro de gotas poss\u00edvel para dar uma boa cobertura e controle, ou seja, de m\u00e9dia a grossa.<br \/>&#8211; A presen\u00e7a nas proximidades de culturas para as quais o produto n\u00e3o esteja registrado, condi\u00e7\u00f5es clim\u00e1ticas, est\u00e1dio de desenvolvimento da cultura, entre outros devem ser considerados como fatores que podem afetar o gerenciamento da deriva e cobertura da planta. Aplicando-se gotas de di\u00e2metro maior reduz-se o potencial de deriva, mas n\u00e3o previne se as aplica\u00e7\u00f5es forem feitas de maneira impr\u00f3pria ou sob condi\u00e7\u00f5es desfavor\u00e1veis.<\/p><p>T\u00e9cnicas gerais para o controle do di\u00e2metro de gotas<\/p><p>&#8211; Volume: use pontas de maior vaz\u00e3o para aplicar o maior volume de calda poss\u00edvel considerando suas necessidades pr\u00e1ticas. Pontas com vaz\u00e3o maior produzem gotas maiores.<\/p><p>&#8211; Press\u00e3o: use a menor press\u00e3o indicada para a ponta. Press\u00f5es maiores reduzem o di\u00e2metro de gotas e n\u00e3o melhoram a penetra\u00e7\u00e3o atrav\u00e9s das folhas da cultura. Quando maiores volumes forem necess\u00e1rios, use pontas de vaz\u00e3o maior ao inv\u00e9s de aumentar a press\u00e3o.<\/p><p>&#8211; Tipo de Ponta: use o modelo de ponta apropriado para o tipo de aplica\u00e7\u00e3o desejada. Para a maioria das pontas, \u00e2ngulos de aplica\u00e7\u00e3o maiores produzem gotas maiores. Considere o uso de pontas de baixa deriva.<\/p><p>&#8211; O equipamento de aplica\u00e7\u00e3o deve estar em perfeitas condi\u00e7\u00f5es de funcionamento, isento de desgaste e vazamentos.<\/p><p>\u00a0<\/p><p>Ventos<\/p><p>A aplica\u00e7\u00e3o a\u00e9rea deve ser realizada quando a velocidade do vento for superior a 3,0 km\/h e n\u00e3o ultrapassar 10 km\/h.<\/p><p>Temperatura e Umidade<\/p><p>Em condi\u00e7\u00f5es de clima quente e seco regule o equipamento para produzir gotas maiores a fim de evitar a evapora\u00e7\u00e3o.<\/p><p>Invers\u00e3o t\u00e9rmica<\/p><p>O potencial de deriva \u00e9 alto durante uma invers\u00e3o t\u00e9rmica. Invers\u00f5es t\u00e9rmicas diminuem o movimento vertical do ar, formando uma nuvem de pequenas gotas suspensas que permanecem perto do solo e com movimento lateral. Invers\u00f5es t\u00e9rmicas s\u00e3o caracterizadas pela eleva\u00e7\u00e3o da temperatura com rela\u00e7\u00e3o \u00e0 altitude e s\u00e3o comuns em noites com poucas nuvens e pouco ou nenhum vento. Elas come\u00e7am a ser formadas ao p\u00f4r do sol e frequentemente continuam at\u00e9 a manh\u00e3 seguinte. Sua presen\u00e7a pode ser identificada pela neblina no n\u00edvel do solo. No entanto, se n\u00e3o houver neblina as invers\u00f5es t\u00e9rmicas podem ser identificadas pelo movimento da fuma\u00e7a origin\u00e1ria de uma fonte no solo. A forma\u00e7\u00e3o de uma nuvem de fuma\u00e7a em camadas e com movimento lateral indica a presen\u00e7a de uma invers\u00e3o t\u00e9rmica; enquanto que se a fuma\u00e7a for rapidamente dispersa e com movimento ascendente, h\u00e1 indica\u00e7\u00e3o de um bom movimento vertical de ar.<\/p><p>INTERVALO DE REENTRADA DE PESSOAS NAS CULTURAS E \u00c1REAS TRATADAS<\/p><p>N\u00e3o entre na \u00e1rea em que o produto foi aplicado antes da secagem completa da calda (no m\u00ednimo 24 horas ap\u00f3s a aplica\u00e7\u00e3o). Caso necessite entrar antes desse per\u00edodo, utilize os equipamentos de prote\u00e7\u00e3o individual (EPI&#8217;s) recomendados para o uso durante a aplica\u00e7\u00e3o.<\/p><p>LIMITA\u00c7\u00d5ES DE USO<\/p><p>Os usos do produto est\u00e3o restritos aos indicados no r\u00f3tulo e bula. <br \/>Quando este produto for utilizado nas doses recomendadas, n\u00e3o causar\u00e1 danos \u00e0s culturas indicadas.<br \/>&#8211; Os limites m\u00e1ximos e toler\u00e2ncias de res\u00edduos para as culturas tratadas com este produto podem n\u00e3o ter sido estabelecidas em n\u00edvel internacional ou podem divergir em outros pa\u00edses, em rela\u00e7\u00e3o aos valores estabelecidos no Brasil. <br \/>Para culturas de exporta\u00e7\u00e3o verifique estas informa\u00e7\u00f5es previamente \u00e0 utiliza\u00e7\u00e3o deste produto.<br \/>&#8211; \u00c9 de inteira responsabilidade do usu\u00e1rio do produto a verifica\u00e7\u00e3o pr\u00e9via destas informa\u00e7\u00f5es, sendo ele o \u00fanico respons\u00e1vel pela decis\u00e3o da exporta\u00e7\u00e3o das culturas tratadas com este produto.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-024bd10 elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"024bd10\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3bf6016\" data-id=\"3bf6016\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0902be6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"0902be6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-940f314\" data-id=\"940f314\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52ef619 elementor-widget elementor-widget-image\" data-id=\"52ef619\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/safeplants.com.br\/wp-content\/uploads\/2021\/08\/pagamento-1-1-1.png\" title=\"pagamento-1-1-1.png\" alt=\"pagamento-1-1-1.png\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4429450\" data-id=\"4429450\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea2dabf elementor-widget elementor-widget-text-editor\" data-id=\"ea2dabf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tLinks\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30d28f3 elementor-align-left elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"30d28f3\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/safeplants.com.br\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/sereena.com.br\/aviso\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aviso Legal<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ev.kapsula.com.br\/status-entrega\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Rastrear Pedido<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/sereena.com.br\/termos\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Termos e Condi\u00e7\u00f5es<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/sereena.com.br\/politica\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pol\u00edtica de Privacidade<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/sereena.com.br\/reembolso\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Reembolso e Devolu\u00e7\u00e3o<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7be2074\" data-id=\"7be2074\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2e92b5 elementor-widget elementor-widget-image\" data-id=\"e2e92b5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" width=\"161\" height=\"47\" src=\"https:\/\/safeplants.com.br\/wp-content\/uploads\/2021\/08\/sac-1-1-1.png\" class=\"attachment-large size-large wp-image-29\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5ad26b elementor-widget elementor-widget-text-editor\" data-id=\"c5ad26b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Servi\u00e7o de atendimento ao consumidor<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cc1e47 elementor-widget elementor-widget-text-editor\" data-id=\"1cc1e47\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Voc\u00ea tem d\u00favidas sobre o nosso produto? Venha conversar conosco!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4824712 elementor-align-left elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4824712\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">suporte@safeplants.com.br<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc63991 elementor-widget elementor-widget-text-editor\" data-id=\"dc63991\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h4>(19) 9 9281-0391<\/h4>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-408521a\" data-id=\"408521a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44b201b elementor-widget elementor-widget-text-editor\" data-id=\"44b201b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tSite 100% seguro\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-160cd22 elementor-widget elementor-widget-image\" data-id=\"160cd22\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/safeplants.com.br\/wp-content\/uploads\/2021\/08\/seguro-1-1-1-1.png\" title=\"seguro-1-1-1-1.png\" alt=\"seguro-1-1-1-1.png\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7dac145 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"7dac145\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0f0f02c\" data-id=\"0f0f02c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef6f213 elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ef6f213\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2023 \u00a9 Sereena. Todos os direitos reservados.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>AVISO LEGAL INSTRU\u00c7\u00d5ES DE USO O produto \u00e9 um inseticida sist\u00eamico do grupo qu\u00edmico dos neocotin\u00f3ides. Classifica\u00e7\u00e3oT\u00e9cnica de Aplica\u00e7\u00e3o:\u00a0TerrestreClasse Agron\u00f4mica:\u00a0InseticidaToxicol\u00f3gica:\u00a04 &#8211; Produto Pouco T\u00f3xicoInflamabilidade:\u00a0N\u00e3o inflam\u00e1velCorrosividade:\u00a0N\u00e3o corrosivoFormula\u00e7\u00e3o:\u00a0Granulado Dispers\u00edvel (WG)Modo de A\u00e7\u00e3o:\u00a0Sist\u00eamico INSTRU\u00c7\u00d5ES DE USO O produto \u00e9 um inseticida do tipo S\u00edlica amorfa. Classifica\u00e7\u00e3oT\u00e9cnica de Aplica\u00e7\u00e3o:\u00a0TerrestreNome qu\u00edmico: silicon dioxide F\u00f3rmula bruta: SiO2 fGrupo qu\u00edmico: Inorg\u00e2nico Classe: Inseticida Classifica\u00e7\u00e3o toxicol\u00f3gica:\u00a0Classe III\u00a0 \u00a0 \u00a0 \u00a0 MODO DE APLICA\u00c7\u00c3O Preparo de Calda Para o preparo da calda, deve-se utilizar \u00e1gua de boa qualidade, livre de coloides em suspens\u00e3o (terra, argila ou mat\u00e9ria org\u00e2nica), a presen\u00e7a destes pode reduzir a efic\u00e1cia do produto.O equipamento de pulveriza\u00e7\u00e3o a ser utilizado para a aplica\u00e7\u00e3o deve estar limpo de res\u00edduos de outro defensivo.Preencher o tanque do pulverizador com \u00e1gua at\u00e9 a metade de sua capacidade; em seguida \u00e9 necess\u00e1rio que se fa\u00e7a uma pr\u00e9-dilui\u00e7\u00e3o em um recipiente n\u00e3o reativo (pl\u00e1stico, fibra de vidro), adicionando a dose recomendada para cada cultivo em 5 a 10 litros de \u00e1gua agitando-o com um bast\u00e3o pl\u00e1stico at\u00e9 que a pr\u00e9-calda esteja homog\u00eanea, assegurando-se a completa umecta\u00e7\u00e3o e dispers\u00e3o dos aglomerantes presentes na formula\u00e7\u00e3o, ap\u00f3s esta etapa, inserir a pr\u00e9-mistura no pulverizador, acrescentar o adjuvante indicado na propor\u00e7\u00e3o recomendada para o cultivo\/alvo e completar a capacidade do reservat\u00f3rio do pulverizador com \u00e1gua, mantendo sempre o sistema em agita\u00e7\u00e3o e retorno ligado durante todo o processo de preparo e pulveriza\u00e7\u00e3o para manter homog\u00eanea a calda de pulveriza\u00e7\u00e3o.Prepare apenas a quantidade de calda necess\u00e1ria para completar o tanque de aplica\u00e7\u00e3o, pulverizando logo ap\u00f3s sua prepara\u00e7\u00e3o.Na ocorr\u00eancia de algum imprevisto que interrompa a agita\u00e7\u00e3o da calda, agit\u00e1-la vigorosamente antes de reiniciar a aplica\u00e7\u00e3o.No caso de quimiga\u00e7\u00e3o considerar a \u00e1rea a ser irrigada, calcular e dosar a quantidade do produto necess\u00e1ria para a aplica\u00e7\u00e3o da dose recomendada por hectare, seguindo a recomenda\u00e7\u00e3o do fabricante do sistema de irriga\u00e7\u00e3o e inje\u00e7\u00e3o. Equipamentos Costais (manuais ou motorizados) Utilizar pulverizador costal dotado de ponta de pulveriza\u00e7\u00e3o do tipo leque (jato plano), calibrando de forma a proporcionar perfeita cobertura com tamanho de gota m\u00e9dia a grossa e direcionando para o alvo desejado.Observar para que a aplica\u00e7\u00e3o seja uniforme e que n\u00e3o ocorram sobreposi\u00e7\u00f5es, escorrimentos e nem deriva por movimentos n\u00e3o planejados pelo operador. Equipamento estacion\u00e1rio manual (pistola) Utilizar pulverizador estacion\u00e1rio munido de barra com ponta de pulveriza\u00e7\u00e3o do tipo leque (jato plano) ou com pistola com gatilho de abertura e fechamento dotado de ponta de pulveriza\u00e7\u00e3o hidr\u00e1ulica e calibrar o equipamento para que a cada acionamento, do gatilho, a vaz\u00e3o seja constante. Manter velocidade de deslocamento constante de modo que n\u00e3o se prejudique a condi\u00e7\u00e3o da forma\u00e7\u00e3o das gotas e mantenha o mesmo volume de calda em toda a \u00e1rea tratada. Realizar movimentos uniformes com a barra ou pistola evitando sobreposi\u00e7\u00f5es, deriva ou concentra\u00e7\u00e3o de calda em um \u00fanico ponto gerando, assim, escorrimento e desperd\u00edcio da calda. Aplica\u00e7\u00e3o em bandeja Utilizar pulverizador costal manual, com volume de calda de 250 mL para bandeja de 200 alv\u00e9olos. O c\u00e1lculo da quantidade de produto a ser aplicado em cada bandeja, dever\u00e1 ser feito previamente e proporcional ao n\u00famero de plantas a ser transplantado por hectare dependendo da cultura e espa\u00e7amento a serem adotados. Logo ap\u00f3s a aplica\u00e7\u00e3o recomenda-se repetir a aplica\u00e7\u00e3o da mesma forma com o mesmo volume de \u00e1gua para que seja feito o arraste do produto das folhas e ramos para o substrato, facilitando a absor\u00e7\u00e3o radicular. Imers\u00e3o e Rega Proceder a imers\u00e3o das bandejas com as mudas durante um per\u00edodo de 30 segundos, em seguida retir\u00e1-las e deixar escorrer o excesso de calda por um per\u00edodo de 2 minutos.Rega: aplicar o produto sobre a planta, nas doses recomendadas, utilizando o volume de 1L de calda\/m\u00b2. Aplica\u00e7\u00e3o via esguicho (drench) Esta modalidade pode ser utilizada ap\u00f3s o transplantio de mudas. Aplicar o produto dilu\u00eddo em \u00e1gua na forma de jato dirigido planta a planta (esguicho) atrav\u00e9s de pulverizador manual, motorizado ou tratorizado, de forma que o produto atinja o caule e escorra at\u00e9 o solo, utilizando o volume de calda por planta e a dosagem recomendada por hectare do produto para o cultivo. Pulverizadores de Barra Utilizar pulverizadores tratorizados de barra ou autopropelidos, com pontas de pulveriza\u00e7\u00e3o hidr\u00e1ulicas, adotando o espa\u00e7amento entre pontas e altura da barra com rela\u00e7\u00e3o ao alvo recomendados pelo fabricante das pontas.Certificar-se que a altura da barra \u00e9 a mesma com rela\u00e7\u00e3o ao alvo em toda sua extens\u00e3o, devendo esta altura ser adequada ao estagio de desenvolvimento da cultura de forma a permitir uma perfeita cobertura das plantas. O equipamento deve ser regulado e calibrado de forma a produzir espectro de gotas m\u00e9dias a grossas. Jato Dirigido Utilizar pulverizador autopropelido ou tratorizado de barra, dotado de ponta do tipo leque (jato plano) dirigido ao sulco de plantio, sobre os &#8220;toletes&#8221;, adotando o espa\u00e7amento entre pontas e altura da barra com rela\u00e7\u00e3o ao alvo que permita uma perfeita cobertura dos \u201ctoletes\u201d. Certificar-se que a altura da barra \u00e9 a mesma com rela\u00e7\u00e3o ao alvo em toda sua extens\u00e3o. O equipamento deve ser regulado e calibrado de forma a produzir espectro de gotas m\u00e9dias a grossas. Procedendo-se a cobertura imediatamente ap\u00f3s aplica\u00e7\u00e3o. Hidropneum\u00e1ticos (Turbo-atomizadores) Utilizar pulverizador tratorizado montado, semi-montado ou de arrasto, dotado de ponta do tipo cone vazio com espa\u00e7amento entre pontas determinado pelo fabricante. As pontas devem ser direcionadas para o alvo de acordo com cada cultura, as pontas superiores e inferiores podem ser desligados para que n\u00e3o seja feita a pulveriza\u00e7\u00e3o no solo ou acima do topo da cultura, al\u00e9m do emprego de pontas com perfil de gotas variando entre grossa e muito grossa nas posi\u00e7\u00f5es superiores, a fim de evitar a perda dessas gotas por deriva. A regulagem do ventilador deve oferecer energia suficiente para que as gotas sejam impulsionadas para o interior do dossel da cultura, conferindo a melhor cobertura no interior da estrutura da planta.O equipamento deve ser regulado e calibrado de forma a produzir espectro de gotas m\u00e9dias a grossas. Irriga\u00e7\u00e3o por gotejamento Iniciar a inje\u00e7\u00e3o da calda com o produto ap\u00f3s o completo funcionamento do sistema de irriga\u00e7\u00e3o. Seguir as<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":"","_joinchat":[]},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/safeplants.com.br\/index.php\/wp-json\/wp\/v2\/pages\/262"}],"collection":[{"href":"https:\/\/safeplants.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/safeplants.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/safeplants.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/safeplants.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=262"}],"version-history":[{"count":6,"href":"https:\/\/safeplants.com.br\/index.php\/wp-json\/wp\/v2\/pages\/262\/revisions"}],"predecessor-version":[{"id":1117,"href":"https:\/\/safeplants.com.br\/index.php\/wp-json\/wp\/v2\/pages\/262\/revisions\/1117"}],"wp:attachment":[{"href":"https:\/\/safeplants.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}